{"id":14143,"date":"2022-02-23T19:29:37","date_gmt":"2022-02-23T18:29:37","guid":{"rendered":"https:\/\/thenailbar.ch\/news-de\/ouverture-a-bale-notre-cadeau-de-bienvenue-50-pour-votre-premiere-visite.html"},"modified":"2022-03-01T11:58:29","modified_gmt":"2022-03-01T10:58:29","slug":"eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch","status":"publish","type":"post","link":"https:\/\/thenailbar.ch\/de\/shops\/2022\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html","title":{"rendered":"ER\u00d6FFNUNG in BASEL! Unser Willkommensgeschenk f\u00fcr Basel 50% f\u00fcr Ihren ersten Besuch ab 1. M\u00e4rz bis 30. April 2022"},"content":{"rendered":"<h2><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14132\" src=\"https:\/\/thenailbar.ch\/wp2\/wp-content\/uploads\/2022\/02\/TNB-BS-NB18-Ouverture-22-004-WPcover-DE.jpg\" alt=\"The Nail Bar Er\u00f6ffning ab 1. M\u00e4rz in Basel Freie Strasse 15\" width=\"750\" height=\"354\" srcset=\"https:\/\/thenailbar.ch\/wp2\/wp-content\/uploads\/2022\/02\/TNB-BS-NB18-Ouverture-22-004-WPcover-DE.jpg 2160w, https:\/\/thenailbar.ch\/wp2\/wp-content\/uploads\/2022\/02\/TNB-BS-NB18-Ouverture-22-004-WPcover-DE-260x123.jpg 260w, https:\/\/thenailbar.ch\/wp2\/wp-content\/uploads\/2022\/02\/TNB-BS-NB18-Ouverture-22-004-WPcover-DE-560x264.jpg 560w, https:\/\/thenailbar.ch\/wp2\/wp-content\/uploads\/2022\/02\/TNB-BS-NB18-Ouverture-22-004-WPcover-DE-768x363.jpg 768w, https:\/\/thenailbar.ch\/wp2\/wp-content\/uploads\/2022\/02\/TNB-BS-NB18-Ouverture-22-004-WPcover-DE-1536x725.jpg 1536w, https:\/\/thenailbar.ch\/wp2\/wp-content\/uploads\/2022\/02\/TNB-BS-NB18-Ouverture-22-004-WPcover-DE-2048x967.jpg 2048w, https:\/\/thenailbar.ch\/wp2\/wp-content\/uploads\/2022\/02\/TNB-BS-NB18-Ouverture-22-004-WPcover-DE-1080x510.jpg 1080w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/h2>\n<h2>Nach vielen Zuschriften und Nachrichten von unseren Kunden ist die Nail Bar zur\u00fcck in Basel!<\/h2>\n<p>Seit fast 2 Jahren sucht die violette Marke nach einem perfekten Ort in dieser wunderbaren Stadt; eingebettet im Herzen der Einkaufsstra\u00dfen, im ersten Stock der Freie Strasse 15 empf\u00e4ngt Sie unser Team der Nail Bar mit einem L\u00e4cheln und Professionalit\u00e4t.<\/p>\n<p>Seit 2010 ist The Nail Bar der Schweizer Marktf\u00fchrer f\u00fcr H\u00e4nde und F\u00fcsse mit Dutzendtausenden zufriedener Kunden. Von Genf bis Z\u00fcrich und jetzt endlich in Basel. Lassen Sie sich von unseren 150 Farben zur Auswahl verf\u00fchren! Ein normaler Lack, ein Semi-Permanent oder Gel? Wir haben alles, was Sie brauchen, vom einfachsten bis zum luxuri\u00f6sesten. Lassen Sie sich \u00fcberzeugen, Testen Sie uns!<\/p>\n<h3>The Brow Bar ist nun auch in Basel<\/h3>\n<p>Eine weitere gute Nachricht, <strong><a href=\"https:\/\/thebrowbar.ch\" target=\"_blank\" rel=\"noopener\">The Brow Bar<\/a><\/strong>, die zweite Marke des Unternehmens, wird auch an der Freie Strasse 15 pr\u00e4sent sein! The Brow Bar ist auch DIE Schweizer Marke, die sich auf Haarentfernung, Augenbrauen und die Sch\u00f6nheit der Wimpern spezialisiert hat. <strong><a href=\"https:\/\/thebrowbar.ch\" target=\"_blank\" rel=\"noopener\">The Brow Bar<\/a><\/strong> ist seit 2014 Experte f\u00fcr Make-up und hat 6 Gesch\u00e4fte in Genf (2), Lausanne, Neuch\u00e2tel, Bern und jetzt Basel.<\/p>\n<h3>Unser Willkommensgeschenk f\u00fcr Basel<\/h3>\n<p>Als Willkommensgeschenk erhalten Sie<strong> ab 1. M\u00e4rz bis 30. April bei Ihrem ersten Besuch 50% Rabatt auf ALLE Behandlungen<\/strong>. Damit Sie sich ein eigenes Bild von unserer Expertise machen k\u00f6nnen, bieten wir Ihnen auf Ihre erste Rechnung ein unschlagbares Geschenk <em>(Angebot g\u00fcltig nur in Basel, exklusive Produktkauf und Geschenkgutschein, Konditionen im Gesch\u00e4ft lesen)<\/em>.<\/p>\n<p><a href=\"https:\/\/thenailbar.ch\/de\/the-nail-bars\/basel-freie-strasse-15\"><strong>Willkommen in der NailBar in Basel!<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach vielen Zuschriften und Nachrichten von unseren Kunden ist die Nail Bar zur\u00fcck in Basel! Seit fast 2 Jahren sucht die violette Marke nach einem perfekten Ort in dieser wunderbaren Stadt; eingebettet im Herzen der Einkaufsstra\u00dfen, im ersten Stock der Freie Strasse 15 empf\u00e4ngt Sie unser Team der Nail Bar mit einem L\u00e4cheln und Professionalit\u00e4t. &hellip; <a href=\"https:\/\/thenailbar.ch\/de\/shops\/2022\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html\">Continued<\/a><\/p>\n","protected":false},"author":1,"featured_media":14129,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","ai_generated_summary":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_members_access_role":[],"_members_access_error":""},"categories":[263],"tags":[],"class_list":["post-14143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shops"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ER\u00d6FFNUNG in BASEL! Unser Willkommensgeschenk f\u00fcr Basel 50% f\u00fcr Ihren ersten Besuch ab 1. M\u00e4rz bis 30. April 2022 - The Nail Bar - Lausanne Genf Vevey Neuenburg Freiburg Monthey Biel Zuerich<\/title>\n<meta name=\"description\" content=\"Er\u00f6ffnung in Basel Unser Willkommensgeschenk 50% f\u00fcr Ihren ersten Besuch ab 1. M\u00e4rz bis 30. April. Damit Sie sich ein eigenes Bild von unserer Expertise machen k\u00f6nnen, bieten wir Ihnen auf Ihre erste Rechnung ein unschlagbares Geschenk\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thenailbar.ch\/de\/shops\/2022\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ER\u00d6FFNUNG in BASEL! Unser Willkommensgeschenk f\u00fcr Basel 50% f\u00fcr Ihren ersten Besuch ab 1. M\u00e4rz bis 30. April 2022\" \/>\n<meta property=\"og:description\" content=\"Als Willkommensgeschenk erhalten Sie ab 1. M\u00e4rz bis 30. April bei Ihrem ersten Besuch 50% Rabatt auf ALLE Behandlungen. Damit Sie sich ein eigenes Bild von unserer Expertise machen k\u00f6nnen, bieten wir Ihnen auf Ihre erste Rechnung ein unschlagbares Geschenk\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thenailbar.ch\/de\/shops\/2022\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html\" \/>\n<meta property=\"og:site_name\" content=\"The Nail Bar - Lausanne Genf Vevey Neuenburg Freiburg Monthey Biel Zuerich\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/thenailbar.nail.switzerland\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-23T18:29:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-01T10:58:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thenailbar.ch\/wp2\/wp-content\/uploads\/2022\/02\/TNB-BS-NB18-Ouverture-22-004-WPcover-DE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2160\" \/>\n\t<meta property=\"og:image:height\" content=\"1020\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rapha\u00ebl Cornuz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheNailBarSwiss\" \/>\n<meta name=\"twitter:site\" content=\"@TheNailBarSwiss\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rapha\u00ebl Cornuz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thenailbar.ch\\\/de\\\/shops\\\/2022\\\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thenailbar.ch\\\/de\\\/shops\\\/2022\\\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html\"},\"author\":{\"name\":\"Rapha\u00ebl Cornuz\",\"@id\":\"https:\\\/\\\/thenailbar.ch\\\/de#\\\/schema\\\/person\\\/540c4e5d6c8983ee4cd66d8f4745c051\"},\"headline\":\"ER\u00d6FFNUNG in BASEL! Unser Willkommensgeschenk f\u00fcr Basel 50% f\u00fcr Ihren ersten Besuch ab 1. M\u00e4rz bis 30. April 2022\",\"datePublished\":\"2022-02-23T18:29:37+00:00\",\"dateModified\":\"2022-03-01T10:58:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thenailbar.ch\\\/de\\\/shops\\\/2022\\\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html\"},\"wordCount\":280,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/thenailbar.ch\\\/de#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/thenailbar.ch\\\/de\\\/shops\\\/2022\\\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thenailbar.ch\\\/wp2\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/TNB-BS-NB18-Ouverture-22-004-WPcover-FR.jpg\",\"articleSection\":[\"Shops\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/thenailbar.ch\\\/de\\\/shops\\\/2022\\\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thenailbar.ch\\\/de\\\/shops\\\/2022\\\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html\",\"url\":\"https:\\\/\\\/thenailbar.ch\\\/de\\\/shops\\\/2022\\\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html\",\"name\":\"ER\u00d6FFNUNG in BASEL! Unser Willkommensgeschenk f\u00fcr Basel 50% f\u00fcr Ihren ersten Besuch ab 1. M\u00e4rz bis 30. April 2022 - The Nail Bar - Lausanne Genf Vevey Neuenburg Freiburg Monthey Biel Zuerich\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thenailbar.ch\\\/de#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thenailbar.ch\\\/de\\\/shops\\\/2022\\\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thenailbar.ch\\\/de\\\/shops\\\/2022\\\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thenailbar.ch\\\/wp2\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/TNB-BS-NB18-Ouverture-22-004-WPcover-FR.jpg\",\"datePublished\":\"2022-02-23T18:29:37+00:00\",\"dateModified\":\"2022-03-01T10:58:29+00:00\",\"description\":\"Er\u00f6ffnung in Basel Unser Willkommensgeschenk 50% f\u00fcr Ihren ersten Besuch ab 1. M\u00e4rz bis 30. April. Damit Sie sich ein eigenes Bild von unserer Expertise machen k\u00f6nnen, bieten wir Ihnen auf Ihre erste Rechnung ein unschlagbares Geschenk\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thenailbar.ch\\\/de\\\/shops\\\/2022\\\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thenailbar.ch\\\/de\\\/shops\\\/2022\\\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/thenailbar.ch\\\/de\\\/shops\\\/2022\\\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html#primaryimage\",\"url\":\"https:\\\/\\\/thenailbar.ch\\\/wp2\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/TNB-BS-NB18-Ouverture-22-004-WPcover-FR.jpg\",\"contentUrl\":\"https:\\\/\\\/thenailbar.ch\\\/wp2\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/TNB-BS-NB18-Ouverture-22-004-WPcover-FR.jpg\",\"width\":2160,\"height\":1020},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thenailbar.ch\\\/de\\\/shops\\\/2022\\\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/thenailbar.ch\\\/de\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ER\u00d6FFNUNG in BASEL! Unser Willkommensgeschenk f\u00fcr Basel 50% f\u00fcr Ihren ersten Besuch ab 1. M\u00e4rz bis 30. April 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thenailbar.ch\\\/de#website\",\"url\":\"https:\\\/\\\/thenailbar.ch\\\/de\",\"name\":\"The Nail Bar - Sans ou Avec rendez-vous!\",\"description\":\"\u201cOhne oder Mit Termin!\u201d\",\"publisher\":{\"@id\":\"https:\\\/\\\/thenailbar.ch\\\/de#organization\"},\"alternateName\":\"The Nail Bar\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thenailbar.ch\\\/de?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thenailbar.ch\\\/de#organization\",\"name\":\"The Nail Bar\",\"url\":\"https:\\\/\\\/thenailbar.ch\\\/de\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/thenailbar.ch\\\/de#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/thenailbar.ch\\\/wp2\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/android-chrome-192x192.png?fit=192%2C192&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/thenailbar.ch\\\/wp2\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/android-chrome-192x192.png?fit=192%2C192&ssl=1\",\"width\":192,\"height\":192,\"caption\":\"The Nail Bar\"},\"image\":{\"@id\":\"https:\\\/\\\/thenailbar.ch\\\/de#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/thenailbar.nail.switzerland\\\/\",\"https:\\\/\\\/x.com\\\/TheNailBarSwiss\",\"https:\\\/\\\/www.instagram.com\\\/thenailbarswitzerland\\\/\",\"https:\\\/\\\/www.pinterest.ch\\\/thenailbarswitzerland\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCAZSdCTBJp-1F91xL1wZHQg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thenailbar.ch\\\/de#\\\/schema\\\/person\\\/540c4e5d6c8983ee4cd66d8f4745c051\",\"name\":\"Rapha\u00ebl Cornuz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba2434b1e1b40a90131bc1f1ecafd649730f36aca8c8ecb3e2d5899593b4165?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba2434b1e1b40a90131bc1f1ecafd649730f36aca8c8ecb3e2d5899593b4165?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba2434b1e1b40a90131bc1f1ecafd649730f36aca8c8ecb3e2d5899593b4165?s=96&d=mm&r=g\",\"caption\":\"Rapha\u00ebl Cornuz\"},\"sameAs\":[\"https:\\\/\\\/cornuz.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ER\u00d6FFNUNG in BASEL! Unser Willkommensgeschenk f\u00fcr Basel 50% f\u00fcr Ihren ersten Besuch ab 1. M\u00e4rz bis 30. April 2022 - The Nail Bar - Lausanne Genf Vevey Neuenburg Freiburg Monthey Biel Zuerich","description":"Er\u00f6ffnung in Basel Unser Willkommensgeschenk 50% f\u00fcr Ihren ersten Besuch ab 1. M\u00e4rz bis 30. April. Damit Sie sich ein eigenes Bild von unserer Expertise machen k\u00f6nnen, bieten wir Ihnen auf Ihre erste Rechnung ein unschlagbares Geschenk","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thenailbar.ch\/de\/shops\/2022\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html","og_locale":"de_DE","og_type":"article","og_title":"ER\u00d6FFNUNG in BASEL! Unser Willkommensgeschenk f\u00fcr Basel 50% f\u00fcr Ihren ersten Besuch ab 1. M\u00e4rz bis 30. April 2022","og_description":"Als Willkommensgeschenk erhalten Sie ab 1. M\u00e4rz bis 30. April bei Ihrem ersten Besuch 50% Rabatt auf ALLE Behandlungen. Damit Sie sich ein eigenes Bild von unserer Expertise machen k\u00f6nnen, bieten wir Ihnen auf Ihre erste Rechnung ein unschlagbares Geschenk","og_url":"https:\/\/thenailbar.ch\/de\/shops\/2022\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html","og_site_name":"The Nail Bar - Lausanne Genf Vevey Neuenburg Freiburg Monthey Biel Zuerich","article_publisher":"https:\/\/www.facebook.com\/thenailbar.nail.switzerland\/","article_published_time":"2022-02-23T18:29:37+00:00","article_modified_time":"2022-03-01T10:58:29+00:00","og_image":[{"width":2160,"height":1020,"url":"https:\/\/thenailbar.ch\/wp2\/wp-content\/uploads\/2022\/02\/TNB-BS-NB18-Ouverture-22-004-WPcover-DE.jpg","type":"image\/jpeg"}],"author":"Rapha\u00ebl Cornuz","twitter_card":"summary_large_image","twitter_creator":"@TheNailBarSwiss","twitter_site":"@TheNailBarSwiss","twitter_misc":{"Verfasst von":"Rapha\u00ebl Cornuz","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thenailbar.ch\/de\/shops\/2022\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html#article","isPartOf":{"@id":"https:\/\/thenailbar.ch\/de\/shops\/2022\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html"},"author":{"name":"Rapha\u00ebl Cornuz","@id":"https:\/\/thenailbar.ch\/de#\/schema\/person\/540c4e5d6c8983ee4cd66d8f4745c051"},"headline":"ER\u00d6FFNUNG in BASEL! Unser Willkommensgeschenk f\u00fcr Basel 50% f\u00fcr Ihren ersten Besuch ab 1. M\u00e4rz bis 30. April 2022","datePublished":"2022-02-23T18:29:37+00:00","dateModified":"2022-03-01T10:58:29+00:00","mainEntityOfPage":{"@id":"https:\/\/thenailbar.ch\/de\/shops\/2022\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html"},"wordCount":280,"commentCount":0,"publisher":{"@id":"https:\/\/thenailbar.ch\/de#organization"},"image":{"@id":"https:\/\/thenailbar.ch\/de\/shops\/2022\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html#primaryimage"},"thumbnailUrl":"https:\/\/thenailbar.ch\/wp2\/wp-content\/uploads\/2022\/02\/TNB-BS-NB18-Ouverture-22-004-WPcover-FR.jpg","articleSection":["Shops"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/thenailbar.ch\/de\/shops\/2022\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/thenailbar.ch\/de\/shops\/2022\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html","url":"https:\/\/thenailbar.ch\/de\/shops\/2022\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html","name":"ER\u00d6FFNUNG in BASEL! Unser Willkommensgeschenk f\u00fcr Basel 50% f\u00fcr Ihren ersten Besuch ab 1. M\u00e4rz bis 30. April 2022 - The Nail Bar - Lausanne Genf Vevey Neuenburg Freiburg Monthey Biel Zuerich","isPartOf":{"@id":"https:\/\/thenailbar.ch\/de#website"},"primaryImageOfPage":{"@id":"https:\/\/thenailbar.ch\/de\/shops\/2022\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html#primaryimage"},"image":{"@id":"https:\/\/thenailbar.ch\/de\/shops\/2022\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html#primaryimage"},"thumbnailUrl":"https:\/\/thenailbar.ch\/wp2\/wp-content\/uploads\/2022\/02\/TNB-BS-NB18-Ouverture-22-004-WPcover-FR.jpg","datePublished":"2022-02-23T18:29:37+00:00","dateModified":"2022-03-01T10:58:29+00:00","description":"Er\u00f6ffnung in Basel Unser Willkommensgeschenk 50% f\u00fcr Ihren ersten Besuch ab 1. M\u00e4rz bis 30. April. Damit Sie sich ein eigenes Bild von unserer Expertise machen k\u00f6nnen, bieten wir Ihnen auf Ihre erste Rechnung ein unschlagbares Geschenk","breadcrumb":{"@id":"https:\/\/thenailbar.ch\/de\/shops\/2022\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thenailbar.ch\/de\/shops\/2022\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/thenailbar.ch\/de\/shops\/2022\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html#primaryimage","url":"https:\/\/thenailbar.ch\/wp2\/wp-content\/uploads\/2022\/02\/TNB-BS-NB18-Ouverture-22-004-WPcover-FR.jpg","contentUrl":"https:\/\/thenailbar.ch\/wp2\/wp-content\/uploads\/2022\/02\/TNB-BS-NB18-Ouverture-22-004-WPcover-FR.jpg","width":2160,"height":1020},{"@type":"BreadcrumbList","@id":"https:\/\/thenailbar.ch\/de\/shops\/2022\/eroffnung-in-basel-unser-willkommensgeschenk-50-fur-ihren-ersten-besuch.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/thenailbar.ch\/de"},{"@type":"ListItem","position":2,"name":"ER\u00d6FFNUNG in BASEL! Unser Willkommensgeschenk f\u00fcr Basel 50% f\u00fcr Ihren ersten Besuch ab 1. M\u00e4rz bis 30. April 2022"}]},{"@type":"WebSite","@id":"https:\/\/thenailbar.ch\/de#website","url":"https:\/\/thenailbar.ch\/de","name":"The Nail Bar - Sans ou Avec rendez-vous!","description":"\u201cOhne oder Mit Termin!\u201d","publisher":{"@id":"https:\/\/thenailbar.ch\/de#organization"},"alternateName":"The Nail Bar","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thenailbar.ch\/de?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/thenailbar.ch\/de#organization","name":"The Nail Bar","url":"https:\/\/thenailbar.ch\/de","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/thenailbar.ch\/de#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/thenailbar.ch\/wp2\/wp-content\/uploads\/2018\/09\/android-chrome-192x192.png?fit=192%2C192&ssl=1","contentUrl":"https:\/\/i0.wp.com\/thenailbar.ch\/wp2\/wp-content\/uploads\/2018\/09\/android-chrome-192x192.png?fit=192%2C192&ssl=1","width":192,"height":192,"caption":"The Nail Bar"},"image":{"@id":"https:\/\/thenailbar.ch\/de#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/thenailbar.nail.switzerland\/","https:\/\/x.com\/TheNailBarSwiss","https:\/\/www.instagram.com\/thenailbarswitzerland\/","https:\/\/www.pinterest.ch\/thenailbarswitzerland\/","https:\/\/www.youtube.com\/channel\/UCAZSdCTBJp-1F91xL1wZHQg"]},{"@type":"Person","@id":"https:\/\/thenailbar.ch\/de#\/schema\/person\/540c4e5d6c8983ee4cd66d8f4745c051","name":"Rapha\u00ebl Cornuz","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/8ba2434b1e1b40a90131bc1f1ecafd649730f36aca8c8ecb3e2d5899593b4165?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ba2434b1e1b40a90131bc1f1ecafd649730f36aca8c8ecb3e2d5899593b4165?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ba2434b1e1b40a90131bc1f1ecafd649730f36aca8c8ecb3e2d5899593b4165?s=96&d=mm&r=g","caption":"Rapha\u00ebl Cornuz"},"sameAs":["https:\/\/cornuz.com"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/thenailbar.ch\/wp2\/wp-content\/uploads\/2022\/02\/TNB-BS-NB18-Ouverture-22-004-WPcover-FR.jpg","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/patLF0-3G7","_links":{"self":[{"href":"https:\/\/thenailbar.ch\/de\/wp-json\/wp\/v2\/posts\/14143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thenailbar.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thenailbar.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thenailbar.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thenailbar.ch\/de\/wp-json\/wp\/v2\/comments?post=14143"}],"version-history":[{"count":5,"href":"https:\/\/thenailbar.ch\/de\/wp-json\/wp\/v2\/posts\/14143\/revisions"}],"predecessor-version":[{"id":14149,"href":"https:\/\/thenailbar.ch\/de\/wp-json\/wp\/v2\/posts\/14143\/revisions\/14149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thenailbar.ch\/de\/wp-json\/wp\/v2\/media\/14129"}],"wp:attachment":[{"href":"https:\/\/thenailbar.ch\/de\/wp-json\/wp\/v2\/media?parent=14143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thenailbar.ch\/de\/wp-json\/wp\/v2\/categories?post=14143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thenailbar.ch\/de\/wp-json\/wp\/v2\/tags?post=14143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}